{"id":11574,"date":"2025-08-14T11:45:11","date_gmt":"2025-08-14T11:45:11","guid":{"rendered":"https:\/\/viande-halal.fr\/mutzig\/?page_id=11574"},"modified":"2025-11-25T13:44:54","modified_gmt":"2025-11-25T13:44:54","slug":"notre-histoire-pro-inter","status":"publish","type":"page","link":"https:\/\/prointer.fr\/mutzig\/notre-histoire-pro-inter\/","title":{"rendered":"Notre histoire"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11574\" class=\"elementor elementor-11574\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1c2d6a e-flex e-con-boxed e-con e-parent\" data-id=\"c1c2d6a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c4dd3cf elementor-cta--skin-cover elementor-cta--valign-middle elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"c4dd3cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_5-1024x295.jpg);\" role=\"img\" aria-label=\"Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_5\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tL'enseigne : Pro-Inter\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tD\u00e9couvrez notre enseigne et notre vision\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9a722aa e-flex e-con-boxed e-con e-parent\" data-id=\"9a722aa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c8c9a37 e-con-full e-flex e-con e-child\" data-id=\"c8c9a37\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8963db elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"a8963db\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;marker&quot;:&quot;underline_zigzag&quot;,&quot;highlighted_text&quot;:&quot;depuis 1985&quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2 class=\"elementor-headline\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">D\u00e9couvrez Pro-Inter, une aventure familiale <\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">depuis 1985<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fffc7a1 elementor-widget elementor-widget-text-editor\" data-id=\"fffc7a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Depuis pr\u00e8s de 40 ans, Pro-Inter est une entreprise familiale pionni\u00e8re dans la boucherie halal en Alsace. N\u00e9e en 1985, notre enseigne a su \u00e9voluer et s\u2019adapter aux besoins d\u2019une client\u00e8le toujours plus diverse, pour devenir aujourd\u2019hui un r\u00e9seau de 11 supermarch\u00e9s dans le Grand Est, et \u00e0 Belfort.<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Chez Pro-Inter, nous sommes fiers de notre histoire et de nos racines : ce qui a commenc\u00e9 comme une boucherie halal s\u2019est transform\u00e9 en un v\u00e9ritable supermarch\u00e9 de r\u00e9f\u00e9rence, o\u00f9 la qualit\u00e9, la diversit\u00e9 et la confiance sont au c\u0153ur de tout.<\/span><\/p>\n<p>\u00a0<\/p>\n<h3 class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Une offre unique pour tous les go\u00fbts<\/span><\/h3>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Avec plus de 6 000 r\u00e9f\u00e9rences soigneusement s\u00e9lectionn\u00e9es, nous proposons une large gamme de produits frais, surgel\u00e9s, \u00e9pices, fruits et l\u00e9gumes, cr\u00e8merie, et bien s\u00fbr, un vaste rayon boucherie halal certifi\u00e9e. Nous mettons un point d\u2019honneur \u00e0 offrir \u00e0 nos clients des produits de grandes marques, autant nationales qu\u2019internationales.<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Cette diversit\u00e9 permet \u00e0 chacun de trouver des produits qui lui ressemblent, des saveurs traditionnelles aux d\u00e9couvertes exotiques, dans une ambiance conviviale et authentique.<\/span><\/p>\n<p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a91587 e-con-full elementor-hidden-laptop elementor-hidden-mobile e-flex e-con e-child\" data-id=\"6a91587\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b86cce4 elementor-widget elementor-widget-heading\" data-id=\"b86cce4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nos autres magasins <\/br>\nPro-Inter<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bad403 elementor-widget elementor-widget-text-editor\" data-id=\"9bad403\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>8 SUPERMARCH\u00c9S DANS LE BAS-RHIN :<\/strong><br \/>\u2022\u00a0Illkirch-Graffenstaden<br \/>\u2022\u00a0Mutzig<br \/>\u2022\u00a0Schiltigheim<br \/>\u2022\u00a0Schweighouse<br \/>\u2022\u00a0Strasbourg Hautepierre<br \/>\u2022\u00a0Strasbourg la Meinau<br \/>\u2022\u00a0Strasbourg\u00a0 Montagne Verte\u00a0<br \/>\u2022 Lingolsheim<\/p>\n<p>\u00a0<\/p>\n<p><strong>2 SUPERMARCH\u00c9S DANS LE HAUT-RHIN :<\/strong><br \/>\u2022\u00a0Pfastatt<br \/>\u2022\u00a0Wittenheim<\/p>\n<p><strong>1 SUPERMARCH\u00c9 DANS LE TERRITOIRE DE BELFORT :<\/strong><br \/>\u2022 Bessoncourt\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-700b0dc elementor-hidden-laptop elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"700b0dc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b12ffbc e-transform elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"b12ffbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_1.jpg\" alt=\"Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne-1.jpg\" alt=\"Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_3.jpg\" alt=\"Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_3\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_4.jpg\" alt=\"Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_4\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_5.jpg\" alt=\"Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_5\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_6.jpg\" alt=\"Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_6\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 sur 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_7.jpg\" alt=\"Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_7\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 sur 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_8.jpg\" alt=\"Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_8\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f329cd elementor-hidden-desktop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile_extra e-flex e-con-boxed e-con e-parent\" data-id=\"7f329cd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4785fdd e-transform elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"4785fdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Caroussel_Enseigne_Mobile_07.jpg\" alt=\"Caroussel_Enseigne_Mobile_07\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Caroussel_Enseigne_Mobile_06.jpg\" alt=\"Caroussel_Enseigne_Mobile_06\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Caroussel_Enseigne_Mobile_05.jpg\" alt=\"Caroussel_Enseigne_Mobile_05\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Caroussel_Enseigne_Mobile_04.jpg\" alt=\"Caroussel_Enseigne_Mobile_04\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Caroussel_Enseigne_Mobile_03.jpg\" alt=\"Caroussel_Enseigne_Mobile_03\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Caroussel_Enseigne_Mobile_02.jpg\" alt=\"Caroussel_Enseigne_Mobile_02\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Caroussel_Enseigne_Mobile_01.jpg\" alt=\"Caroussel_Enseigne_Mobile_01\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5141206 e-flex e-con-boxed e-con e-parent\" data-id=\"5141206\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-252905f e-con-full e-flex e-con e-child\" data-id=\"252905f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-729c3fa e-con-full e-flex e-con e-child\" data-id=\"729c3fa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b993d2d elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"b993d2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;highlighted_text&quot;:&quot;6000 &quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;marker&quot;:&quot;circle&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-headline\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Plus de <\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">6000 <\/span>\n\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\"><\/br> r\u00e9f\u00e9rences<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74c6639 elementor-widget elementor-widget-text-editor\" data-id=\"74c6639\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Large gamme de produits frais et de qualit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4e90e72 e-con-full e-flex e-con e-child\" data-id=\"4e90e72\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-cdc7159 e-con-full e-flex e-con e-child\" data-id=\"cdc7159\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afa8f35 elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"afa8f35\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;highlighted_text&quot;:&quot;40 ans&quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;marker&quot;:&quot;circle&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-headline\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Plus de <\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">40 ans<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\"><\/br> d'exp\u00e9rience<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6545f80 elementor-widget elementor-widget-text-editor\" data-id=\"6545f80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>+40 ans que le groupe Pro-Inter satisfait ses clients.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-22d032c e-con-full e-flex e-con e-child\" data-id=\"22d032c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-79f882c e-con-full e-flex e-con e-child\" data-id=\"79f882c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-806975d elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"806975d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;highlighted_text&quot;:&quot;200 000&quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;marker&quot;:&quot;circle&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-headline\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Plus de <\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">200 000<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\"><\/br> clients fid\u00e8les<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-949dcd1 elementor-widget elementor-widget-text-editor\" data-id=\"949dcd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La satisfaction de nos clients est notre priorit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fbcfa73 e-flex e-con-boxed e-con e-parent\" data-id=\"fbcfa73\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-26ef9f6 e-con-full e-flex e-con e-child\" data-id=\"26ef9f6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8eeef2 elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"a8eeef2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;marker&quot;:&quot;underline_zigzag&quot;,&quot;highlighted_text&quot;:&quot;belle r\\u00e9ussite&quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2 class=\"elementor-headline\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Une client\u00e8le fid\u00e8le, notre plus <\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">belle r\u00e9ussite<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c5c9d9 elementor-widget elementor-widget-text-editor\" data-id=\"4c5c9d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"cvGsUA direction-ltr align-start para-style-body\">\u00a0<\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Plus de 200 000 clients fid\u00e8les nous font confiance chaque ann\u00e9e. Cette fid\u00e9lit\u00e9, nous la devons \u00e0 notre exigence sur la qualit\u00e9 des produits, notre \u00e9coute attentive, et notre volont\u00e9 constante d\u2019am\u00e9liorer votre exp\u00e9rience en magasin.<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Nos \u00e9quipes passionn\u00e9es, pr\u00e9sentes dans nos 11 supermarch\u00e9s\u00a0 vous accueillent avec chaleur et professionnalisme.<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Rejoignez l\u2019aventure Pro-Inter !<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Plus qu\u2019un simple supermarch\u00e9, Pro-Inter est une famille. Chaque jour, nous grandissons ensemble en valorisant la diversit\u00e9, la qualit\u00e9, et le respect. Que vous soyez client ou futur collaborateur, nous vous invitons \u00e0 faire partie de cette belle aventure humaine.<\/span><\/p>\n<p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d9ffd40 e-con-full e-flex e-con e-child\" data-id=\"d9ffd40\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bb8b5a7 elementor-widget elementor-widget-image\" data-id=\"bb8b5a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_10.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-11920\" alt=\"\" srcset=\"https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_10.jpg 1000w, https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_10-300x300.jpg 300w, https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_10-150x150.jpg 150w, https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_10-768x768.jpg 768w, https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_10-500x500.jpg 500w, https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_10-900x900.jpg 900w, https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_10-100x100.jpg 100w, https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_10-50x50.jpg 50w, https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_10-460x460.jpg 460w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d0fb32 e-flex e-con-boxed e-con e-parent\" data-id=\"1d0fb32\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fd074ad e-con-full e-flex e-con e-child\" data-id=\"fd074ad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ccf992b elementor-widget elementor-widget-image\" data-id=\"ccf992b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_9-1.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-11922\" alt=\"\" srcset=\"https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_9-1.jpg 1000w, https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_9-1-300x300.jpg 300w, https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_9-1-150x150.jpg 150w, https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_9-1-768x768.jpg 768w, https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_9-1-500x500.jpg 500w, https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_9-1-900x900.jpg 900w, https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_9-1-100x100.jpg 100w, https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_9-1-50x50.jpg 50w, https:\/\/prointer.fr\/mutzig\/wp-content\/uploads\/sites\/12\/2025\/08\/Pro-Inter_Accueil_Magasin_Oriental_Viande-Halal_Grand-Est_Enseigne_9-1-460x460.jpg 460w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3982059 e-con-full e-flex e-con e-child\" data-id=\"3982059\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa563fb elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"fa563fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;marker&quot;:&quot;underline_zigzag&quot;,&quot;highlighted_text&quot;:&quot; la boucherie halal&quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2 class=\"elementor-headline\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Le pionner de <\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\"> la boucherie halal<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">en Alsace<\/span>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6800515 elementor-widget elementor-widget-text-editor\" data-id=\"6800515\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pro-Inter, le leader de la viande halal en Alsace, ce sont 8 magasins dans le Bas-Rhin, 2 dans le Haut-Rhin et 1 en\u00a0 Bourgogne-Franche-Comt\u00e9 !<\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Notre entreprise familiale vous fait b\u00e9n\u00e9ficier de sa riche exp\u00e9rience de pr\u00e8s de 40 ans, aussi bien dans le commerce de la viande halal que des produits internationaux.<\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Pro-Inter, comprenez \u201c<strong>Pro<\/strong>duits-<strong>Inter<\/strong>nationaux\u201d, c\u2019est une offre de plus de 6 000 r\u00e9f\u00e9rences aussi bien import\u00e9es que r\u00e9gionales !<\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>De par notre professionnalisme, nous avons su fid\u00e9liser et convaincre une client\u00e8le en constante \u00e9volution, de plus en plus h\u00e9t\u00e9rog\u00e8ne, \u00e0 la recherche de produits exotiques qui ne sont habituellement pas propos\u00e9s dans la Grande Distribution traditionnelle.<\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Pro-Inter est une entreprise pionni\u00e8re sur le march\u00e9 de l\u2019alimentation halal en Alsace qui compte 9 points de vente dans la r\u00e9gion.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>L&rsquo;enseigne : Pro-Inter D\u00e9couvrez notre enseigne et notre vision D\u00e9couvrez Pro-Inter, une aventure familiale depuis 1985 Depuis pr\u00e8s de 40 ans, Pro-Inter est une entreprise familiale pionni\u00e8re dans la boucherie halal en Alsace. N\u00e9e en 1985, notre enseigne a su \u00e9voluer et s\u2019adapter aux besoins d\u2019une client\u00e8le toujours plus diverse, pour devenir aujourd\u2019hui un r\u00e9seau [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-11574","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/pages\/11574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/comments?post=11574"}],"version-history":[{"count":113,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/pages\/11574\/revisions"}],"predecessor-version":[{"id":13043,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/pages\/11574\/revisions\/13043"}],"wp:attachment":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/media?parent=11574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}