{"id":14485,"date":"2025-11-25T16:03:08","date_gmt":"2025-11-25T16:03:08","guid":{"rendered":"https:\/\/viande-halal.fr\/mutzig\/?post_type=product&#038;p=14485"},"modified":"2025-11-25T16:04:09","modified_gmt":"2025-11-25T16:04:09","slug":"red-bull-fruit-du-dragon-green-edit","status":"publish","type":"product","link":"https:\/\/prointer.fr\/mutzig\/produit\/red-bull-fruit-du-dragon-green-edit\/","title":{"rendered":"RED BULL FRUIT DU DRAGON GREEN EDIT"},"content":{"rendered":"<p>D\u00e9couvrez le Red Bull Fruit du Dragon Green Edit, une d\u00e9licieuse boisson \u00e9nergisante fruit\u00e9e de la marque Red Bull. Cette boisson unique associe l&rsquo;\u00e9nergie revitalisante du Red Bull \u00e0 la saveur exotique et rafra\u00eechissante du fruit du dragon. Parfaite pour vous donner un coup de boost lors de vos journ\u00e9es charg\u00e9es, cette boisson est un v\u00e9ritable concentr\u00e9 d&rsquo;\u00e9nergie et de saveurs.nnLe Red Bull Fruit du Dragon Green Edit est id\u00e9al pour les amateurs de boissons \u00e9nergisantes \u00e0 la recherche d&rsquo;une option savoureuse et stimulante. Son go\u00fbt fruit\u00e9 et acidul\u00e9 en fait une boisson rafra\u00eechissante et revigorante, parfaite pour vous accompagner tout au long de la journ\u00e9e.nnDisponible dans notre supermarch\u00e9 physique, le Red Bull Fruit du Dragon Green Edit est un produit incontournable pour tous ceux qui cherchent \u00e0 allier plaisir et \u00e9nergie. N&rsquo;h\u00e9sitez pas \u00e0 venir d\u00e9couvrir cette nouveaut\u00e9 Red Bull dans notre rayon boissons et laissez-vous s\u00e9duire par son go\u00fbt unique et ses bienfaits \u00e9nergisants. Profitez d\u00e8s maintenant de cette d\u00e9licieuse boisson pour faire le plein d&rsquo;\u00e9nergie et de saveurs !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez le Red Bull Fruit du Dragon Green Edition, une boisson \u00e9nergisante au d\u00e9licieux go\u00fbt de fruit du dragon. Boostez votre \u00e9nergie avec cette boisson revigorante sign\u00e9e Red Bull.<\/p>\n","protected":false},"featured_media":14920,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"product_cat":[76,75],"product_tag":[98],"class_list":["post-14485","product","type-product","status-publish","has-post-thumbnail","product_brand-red-bull","product_cat-boissons","product_cat-tous-les-produits","product_tag-red-bull","product_shipping_class-top-produits","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product\/14485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/comments?post=14485"}],"version-history":[{"count":1,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product\/14485\/revisions"}],"predecessor-version":[{"id":14921,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product\/14485\/revisions\/14921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/media\/14920"}],"wp:attachment":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/media?parent=14485"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product_cat?post=14485"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product_tag?post=14485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}