{"id":14768,"date":"2025-11-25T16:03:34","date_gmt":"2025-11-25T16:03:34","guid":{"rendered":"https:\/\/viande-halal.fr\/mutzig\/?post_type=product&#038;p=14768"},"modified":"2025-11-25T16:03:44","modified_gmt":"2025-11-25T16:03:44","slug":"pates-spaghetti-ankara-500g","status":"publish","type":"product","link":"https:\/\/prointer.fr\/mutzig\/produit\/pates-spaghetti-ankara-500g\/","title":{"rendered":"PATES SPAGHETTI ANKARA &#8211; 500G"},"content":{"rendered":"<p>D\u00e9couvrez les d\u00e9licieuses p\u00e2tes spaghetti Ankara de 500g, parfaites pour un repas savoureux et rapide \u00e0 pr\u00e9parer. La marque Ankara est reconnue pour la qualit\u00e9 de ses produits et ces p\u00e2tes ne font pas exception. Fabriqu\u00e9es \u00e0 partir de bl\u00e9 de qualit\u00e9 sup\u00e9rieure, elles sont id\u00e9ales pour accompagner toutes vos recettes de p\u00e2tes pr\u00e9f\u00e9r\u00e9es.nnLes p\u00e2tes spaghetti Ankara sont un incontournable de toute cuisine, que ce soit pour un plat de p\u00e2tes classique \u00e0 la sauce tomate ou pour une recette plus \u00e9labor\u00e9e. Leur texture ferme et leur go\u00fbt d\u00e9licat en font un choix parfait pour satisfaire toute la famille.nnGr\u00e2ce \u00e0 leur format pratique de 500g, les p\u00e2tes spaghetti Ankara sont id\u00e9ales pour les familles ou pour les repas entre amis. Leur cuisson rapide et facile vous permettra de les pr\u00e9parer en un rien de temps, pour des repas gourmands et conviviaux.nnNe tardez plus \u00e0 ajouter les p\u00e2tes spaghetti Ankara \u00e0 votre panier lors de votre prochaine visite en magasin. Offrez-vous le plaisir de d\u00e9guster des p\u00e2tes de qualit\u00e9 sup\u00e9rieure, pour des repas savoureux et authentiques. Profitez de la qualit\u00e9 Ankara pour sublimer vos plats de p\u00e2tes pr\u00e9f\u00e9r\u00e9s !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez les d\u00e9licieuses p\u00e2tes spaghetti Ankara de 500g, id\u00e9ales pour vos recettes italiennes pr\u00e9f\u00e9r\u00e9es. Fabriqu\u00e9es par la marque Ankara, ces p\u00e2tes sont savoureuses et faciles \u00e0 pr\u00e9parer. Commandez-les maintenant !<\/p>\n","protected":false},"featured_media":14816,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"product_cat":[104,75],"product_tag":[154],"class_list":["post-14768","product","type-product","status-publish","has-post-thumbnail","product_brand-ankara","product_cat-epicerie-salee","product_cat-tous-les-produits","product_tag-ankara","product_shipping_class-top-produits","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product\/14768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/comments?post=14768"}],"version-history":[{"count":1,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product\/14768\/revisions"}],"predecessor-version":[{"id":14817,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product\/14768\/revisions\/14817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/media\/14816"}],"wp:attachment":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/media?parent=14768"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product_cat?post=14768"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product_tag?post=14768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}