{"id":14777,"date":"2025-11-25T16:03:35","date_gmt":"2025-11-25T16:03:35","guid":{"rendered":"https:\/\/viande-halal.fr\/mutzig\/?post_type=product&#038;p=14777"},"modified":"2025-11-25T16:04:58","modified_gmt":"2025-11-25T16:04:58","slug":"pates-tel-sehriye-ankara-500g","status":"publish","type":"product","link":"https:\/\/prointer.fr\/mutzig\/produit\/pates-tel-sehriye-ankara-500g\/","title":{"rendered":"PATES TEL SEHRIYE ANKARA &#8211; 500G"},"content":{"rendered":"<p>Les p\u00e2tes TEL SEHRIYE ANKARA de la marque ANKARA sont des p\u00e2tes traditionnelles turques de qualit\u00e9 sup\u00e9rieure. Avec leur forme unique et leur texture d\u00e9licieusement moelleuse, ces p\u00e2tes sont parfaites pour toutes vos recettes de cuisine m\u00e9diterran\u00e9enne.nnFabriqu\u00e9es \u00e0 partir de semoule de bl\u00e9 dur de premi\u00e8re qualit\u00e9, les p\u00e2tes TEL SEHRIYE ANKARA sont riches en fibres et en nutriments essentiels pour une alimentation \u00e9quilibr\u00e9e. Leur go\u00fbt authentique et leur texture parfaite en font un incontournable de votre garde-manger.nnQue ce soit pour accompagner un plat en sauce, dans une soupe ou en salade, les p\u00e2tes TEL SEHRIYE ANKARA sauront ravir les papilles des plus gourmands. Disponibles en format pratique de 500g, elles sont id\u00e9ales pour toute la famille.nnAjoutez une touche d&rsquo;authenticit\u00e9 \u00e0 vos plats avec les p\u00e2tes TEL SEHRIYE ANKARA de la marque ANKARA, et laissez-vous transporter en Turquie le temps d&rsquo;un repas. Offrez-vous le meilleur de la gastronomie m\u00e9diterran\u00e9enne avec ces d\u00e9licieuses p\u00e2tes, \u00e0 retrouver dans notre rayon \u00e9picerie sal\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez les d\u00e9licieuses p\u00e2tes TEL SEHRIYE ANKARA de qualit\u00e9 sup\u00e9rieure en format de 500g. Parfaites pour des plats savoureux et \u00e9quilibr\u00e9s. Disponibles en ligne. (mots-cl\u00e9s : p\u00e2tes, Ankara, qualit\u00e9)<\/p>\n","protected":false},"featured_media":14101,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"product_cat":[104,75],"product_tag":[154],"class_list":["post-14777","product","type-product","status-publish","has-post-thumbnail","product_brand-ankara","product_cat-epicerie-salee","product_cat-tous-les-produits","product_tag-ankara","product_shipping_class-top-produits","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product\/14777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/comments?post=14777"}],"version-history":[{"count":1,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product\/14777\/revisions"}],"predecessor-version":[{"id":15157,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product\/14777\/revisions\/15157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/media\/14101"}],"wp:attachment":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/media?parent=14777"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product_cat?post=14777"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product_tag?post=14777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}