{"id":14940,"date":"2025-11-25T16:04:11","date_gmt":"2025-11-25T16:04:11","guid":{"rendered":"https:\/\/viande-halal.fr\/mutzig\/?post_type=product&#038;p=14940"},"modified":"2025-11-25T16:04:21","modified_gmt":"2025-11-25T16:04:21","slug":"concentre-tomates-4-4-tukas-830g","status":"publish","type":"product","link":"https:\/\/prointer.fr\/mutzig\/produit\/concentre-tomates-4-4-tukas-830g\/","title":{"rendered":"CONCENTRE TOMATES 4\/4 TUKAS &#8211;  830G"},"content":{"rendered":"<p>D\u00e9couvrez le concentr\u00e9 de tomates 4\/4 Tukas &#8211; 830g, un produit indispensable dans votre cuisine pour apporter une touche de saveur et de couleur \u00e0 vos plats. Fabriqu\u00e9 par la marque renomm\u00e9e Tukas, ce concentr\u00e9 de tomates de qualit\u00e9 sup\u00e9rieure est parfait pour r\u00e9aliser de d\u00e9licieuses sauces, soupes, p\u00e2tes et bien plus encore.nnLe concentr\u00e9 de tomates Tukas est un incontournable de la cat\u00e9gorie \u00e9picerie sal\u00e9e, id\u00e9al pour agr\u00e9menter vos recettes quotidiennes. Son format pratique de 830g vous permet de l&rsquo;utiliser en grande quantit\u00e9 sans avoir \u00e0 vous soucier de manquer de stock.nnLes tomates utilis\u00e9es pour la fabrication de ce concentr\u00e9 sont s\u00e9lectionn\u00e9es avec soin pour garantir une saveur intense et authentique \u00e0 chaque bouch\u00e9e. Avec Tukas, vous pouvez \u00eatre s\u00fbr de servir \u00e0 votre famille et \u00e0 vos invit\u00e9s des plats savoureux et gourmands.nnN&rsquo;h\u00e9sitez pas \u00e0 ajouter le concentr\u00e9 de tomates 4\/4 Tukas &#8211; 830g \u00e0 votre panier lors de votre prochaine visite en magasin. Vos papilles vous remercieront pour cette d\u00e9licieuse d\u00e9couverte culinaire. Commandez d\u00e8s maintenant et sublimez vos plats avec le concentr\u00e9 de tomates Tukas !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez le concentr\u00e9 de tomates 4\/4 Tukas, un incontournable de la cuisine m\u00e9diterran\u00e9enne. Id\u00e9al pour apporter une touche de fra\u00eecheur et de saveur \u00e0 vos plats. Profitez de l&rsquo;authenticit\u00e9 de la marque Tukas.<\/p>\n","protected":false},"featured_media":14980,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"product_cat":[104,75],"product_tag":[173],"class_list":["post-14940","product","type-product","status-publish","has-post-thumbnail","product_brand-tukas","product_cat-epicerie-salee","product_cat-tous-les-produits","product_tag-tukas","product_shipping_class-top-produits","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product\/14940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/comments?post=14940"}],"version-history":[{"count":1,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product\/14940\/revisions"}],"predecessor-version":[{"id":14981,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product\/14940\/revisions\/14981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/media\/14980"}],"wp:attachment":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/media?parent=14940"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product_cat?post=14940"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product_tag?post=14940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}