{"id":15018,"date":"2025-11-25T16:04:33","date_gmt":"2025-11-25T16:04:33","guid":{"rendered":"https:\/\/viande-halal.fr\/mutzig\/?post_type=product&#038;p=15018"},"modified":"2025-11-25T16:04:44","modified_gmt":"2025-11-25T16:04:44","slug":"pois-chiches-suntat-425ml","status":"publish","type":"product","link":"https:\/\/prointer.fr\/mutzig\/produit\/pois-chiches-suntat-425ml\/","title":{"rendered":"POIS CHICHES SUNTAT &#8211; 425ML"},"content":{"rendered":"<p>D\u00e9couvrez les pois chiches SUNTAT en conserve de 425ml, une d\u00e9licieuse option pour agr\u00e9menter vos plats en un clin d&rsquo;\u0153il. Issus de l&rsquo;agriculture biologique, ces pois chiches de qualit\u00e9 sup\u00e9rieure sont soigneusement s\u00e9lectionn\u00e9s pour vous offrir un produit savoureux et sain.nnLes pois chiches sont une excellente source de prot\u00e9ines v\u00e9g\u00e9tales, de fibres et de min\u00e9raux essentiels tels que le fer et le magn\u00e9sium. Leur texture tendre et leur go\u00fbt subtil en font un ingr\u00e9dient polyvalent pouvant \u00eatre ajout\u00e9 \u00e0 de nombreuses recettes, que ce soit des salades, des plats en sauce ou des soupes.nnEn choisissant les pois chiches SUNTAT, vous optez pour un produit de confiance, respectueux de l&rsquo;environnement et de votre sant\u00e9. Faciles \u00e0 conserver et \u00e0 utiliser, ces pois chiches en conserve sont parfaits pour les personnes press\u00e9es ou en manque d&rsquo;inspiration en cuisine.nnAjoutez d\u00e8s maintenant les pois chiches SUNTAT \u00e0 votre panier pour apporter une touche d&rsquo;originalit\u00e9 et de gourmandise \u00e0 vos repas quotidiens. N&rsquo;attendez plus pour profiter de leur saveur authentique et de leurs bienfaits pour votre bien-\u00eatre. Rendez-vous dans votre supermarch\u00e9 pour les d\u00e9couvrir d\u00e8s aujourd&rsquo;hui !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez les pois chiches Suntat en conserve de 425ml, id\u00e9aux pour vos recettes saines et savoureuses. Profitez de la qualit\u00e9 et de la fra\u00eecheur de la marque Suntat.<\/p>\n","protected":false},"featured_media":15057,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"product_cat":[104,75],"product_tag":[94],"class_list":["post-15018","product","type-product","status-publish","has-post-thumbnail","product_brand-suntat","product_cat-epicerie-salee","product_cat-tous-les-produits","product_tag-suntat","product_shipping_class-top-produits","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product\/15018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/comments?post=15018"}],"version-history":[{"count":1,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product\/15018\/revisions"}],"predecessor-version":[{"id":15058,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product\/15018\/revisions\/15058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/media\/15057"}],"wp:attachment":[{"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/media?parent=15018"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product_cat?post=15018"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/prointer.fr\/mutzig\/wp-json\/wp\/v2\/product_tag?post=15018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}